{"id":8287,"date":"2016-02-25T11:57:41","date_gmt":"2016-02-25T11:57:41","guid":{"rendered":"http:\/\/dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2.jpg"},"modified":"2016-02-25T11:57:41","modified_gmt":"2016-02-25T11:57:41","slug":"unnamed-2-2","status":"inherit","type":"attachment","link":"https:\/\/www.dancemogul.com\/news\/unnamed-2-2\/","title":{"rendered":"unnamed (2)"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-8287","attachment","type-attachment","status-inherit","hentry"],"smush":{"stats":{"time":11.9000000000000003552713678800500929355621337890625,"bytes":285705,"percent":24.46000000000000085265128291212022304534912109375,"size_before":1167813,"size_after":882108,"lossy":2,"keep_exif":0,"api_version":"1.0"},"sizes":{"thumbnail":{"time":0.35999999999999998667732370449812151491641998291015625,"bytes":896,"percent":24.879999999999999005240169935859739780426025390625,"size_before":3602,"size_after":2706},"thevoux-style3-small":{"time":0.35999999999999998667732370449812151491641998291015625,"bytes":3068,"percent":27.0799999999999982946974341757595539093017578125,"size_before":11330,"size_after":8262},"thevoux-style9":{"time":0.440000000000000002220446049250313080847263336181640625,"bytes":5666,"percent":29.660000000000000142108547152020037174224853515625,"size_before":19100,"size_after":13434},"thevoux-style1":{"time":0.429999999999999993338661852249060757458209991455078125,"bytes":9092,"percent":30.519999999999999573674358543939888477325439453125,"size_before":29791,"size_after":20699},"medium_large":{"time":0.60999999999999998667732370449812151491641998291015625,"bytes":18942,"percent":32.88000000000000255795384873636066913604736328125,"size_before":57604,"size_after":38662},"woocommerce_thumbnail":{"time":0.39000000000000001332267629550187848508358001708984375,"bytes":1989,"percent":22.64999999999999857891452847979962825775146484375,"size_before":8781,"size_after":6792},"woocommerce_gallery_thumbnail":{"time":0.320000000000000006661338147750939242541790008544921875,"bytes":637,"percent":26.530000000000001136868377216160297393798828125,"size_before":2401,"size_after":1764},"shop_single":{"time":0.5100000000000000088817841970012523233890533447265625,"bytes":11012,"percent":30.10000000000000142108547152020037174224853515625,"size_before":36587,"size_after":25575},"large":{"time":0.58999999999999996891375531049561686813831329345703125,"bytes":14607,"percent":31.4200000000000017053025658242404460906982421875,"size_before":46487,"size_after":31880},"post-thumbnail":{"time":0.38000000000000000444089209850062616169452667236328125,"bytes":1059,"percent":23.030000000000001136868377216160297393798828125,"size_before":4598,"size_after":3539},"thevoux-square":{"time":0.6999999999999999555910790149937383830547332763671875,"bytes":4646,"percent":26.120000000000000994759830064140260219573974609375,"size_before":17790,"size_after":13144},"thevoux-style2":{"time":0.520000000000000017763568394002504646778106689453125,"bytes":18830,"percent":32.86999999999999744204615126363933086395263671875,"size_before":57287,"size_after":38457},"medium":{"time":0.35999999999999998667732370449812151491641998291015625,"bytes":1549,"percent":23.190000000000001278976924368180334568023681640625,"size_before":6680,"size_after":5131},"thevoux-widget":{"time":0.460000000000000019984014443252817727625370025634765625,"bytes":4165,"percent":29.129999999999999005240169935859739780426025390625,"size_before":14296,"size_after":10131},"woocommerce_single":{"time":0.450000000000000011102230246251565404236316680908203125,"bytes":11012,"percent":30.10000000000000142108547152020037174224853515625,"size_before":36587,"size_after":25575},"shop_catalog":{"time":0.340000000000000024424906541753443889319896697998046875,"bytes":1989,"percent":22.64999999999999857891452847979962825775146484375,"size_before":8781,"size_after":6792},"thevoux-masonry":{"time":0.6999999999999999555910790149937383830547332763671875,"bytes":28163,"percent":35.3299999999999982946974341757595539093017578125,"size_before":79707,"size_after":51544},"full":{"time":1.5700000000000000621724893790087662637233734130859375,"bytes":112539,"percent":18.4200000000000017053025658242404460906982421875,"size_before":610912,"size_after":498373},"thevoux-single":{"time":0.5500000000000000444089209850062616169452667236328125,"bytes":16442,"percent":35.409999999999996589394868351519107818603515625,"size_before":46432,"size_after":29990},"thevoux-vertical":{"time":0.65000000000000002220446049250313080847263336181640625,"bytes":6046,"percent":26.620000000000000994759830064140260219573974609375,"size_before":22711,"size_after":16665},"thevoux-style3":{"time":0.5300000000000000266453525910037569701671600341796875,"bytes":9846,"percent":30.17999999999999971578290569595992565155029296875,"size_before":32625,"size_after":22779},"thevoux-megamenu":{"time":0.56999999999999995115018691649311222136020660400390625,"bytes":2873,"percent":25.370000000000000994759830064140260219573974609375,"size_before":11323,"size_after":8450},"shop_thumbnail":{"time":0.11000000000000000055511151231257827021181583404541015625,"bytes":637,"percent":26.530000000000001136868377216160297393798828125,"size_before":2401,"size_after":1764}}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.dancemogul.com\/news\/news\/wp-content\/uploads\/2016\/02\/unnamed-2.jpg' rel=\"mfp\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"300\" src=\"https:\/\/www.dancemogul.com\/news\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-200x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.dancemogul.com\/news\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-200x300.jpg 200w, https:\/\/www.dancemogul.com\/news\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-768x1151.jpg 768w, https:\/\/www.dancemogul.com\/news\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-683x1024.jpg 683w, https:\/\/www.dancemogul.com\/news\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-900x1349.jpg 900w, https:\/\/www.dancemogul.com\/news\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-600x899.jpg 600w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2698,"height":4043,"file":"2016\/02\/unnamed-2.jpg","sizes":{"thumbnail":{"file":"unnamed-2-150x150.jpg","width":150,"height":150,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-150x150.jpg"},"medium":{"file":"unnamed-2-200x300.jpg","width":200,"height":300,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-200x300.jpg"},"medium_large":{"file":"unnamed-2-768x1151.jpg","width":768,"height":1151,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-768x1151.jpg"},"large":{"file":"unnamed-2-683x1024.jpg","width":683,"height":1024,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-683x1024.jpg"},"post-thumbnail":{"file":"unnamed-2-180x180.jpg","width":180,"height":180,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-180x180.jpg"},"thevoux-single":{"file":"unnamed-2-1170x600.jpg","width":1170,"height":600,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-1170x600.jpg"},"thevoux-square":{"file":"unnamed-2-480x480.jpg","width":480,"height":480,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-480x480.jpg"},"thevoux-vertical":{"file":"unnamed-2-480x640.jpg","width":480,"height":640,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-480x640.jpg"},"thevoux-megamenu":{"file":"unnamed-2-480x300.jpg","width":480,"height":300,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-480x300.jpg"},"thevoux-masonry":{"file":"unnamed-2-900x1349.jpg","width":900,"height":1349,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-900x1349.jpg"},"thevoux-style1":{"file":"unnamed-2-740x560.jpg","width":740,"height":560,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-740x560.jpg"},"thevoux-style2":{"file":"unnamed-2-900x900.jpg","width":900,"height":900,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-900x900.jpg"},"thevoux-style3":{"file":"unnamed-2-760x600.jpg","width":760,"height":600,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-760x600.jpg"},"thevoux-style3-small":{"file":"unnamed-2-540x280.jpg","width":540,"height":280,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-540x280.jpg"},"thevoux-style9":{"file":"unnamed-2-670x400.jpg","width":670,"height":400,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-670x400.jpg"},"thevoux-widget":{"file":"unnamed-2-680x300.jpg","width":680,"height":300,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-680x300.jpg"},"woocommerce_thumbnail":{"file":"unnamed-2-300x300.jpg","width":300,"height":300,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-300x300.jpg"},"woocommerce_single":{"file":"unnamed-2-600x899.jpg","width":600,"height":899,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-600x899.jpg"},"woocommerce_gallery_thumbnail":{"file":"unnamed-2-100x100.jpg","width":100,"height":100,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-100x100.jpg"},"shop_catalog":{"file":"unnamed-2-300x300.jpg","width":300,"height":300,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-300x300.jpg"},"shop_single":{"file":"unnamed-2-600x899.jpg","width":600,"height":899,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-600x899.jpg"},"shop_thumbnail":{"file":"unnamed-2-100x100.jpg","width":100,"height":100,"filesize":0,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2-100x100.jpg"},"full":{"file":"unnamed-2.jpg","width":2698,"height":4043,"mime_type":"image\/jpeg","source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"filesize":610912},"post":null,"source_url":"https:\/\/www.dancemogul.com\/news\/wp-content\/uploads\/2016\/02\/unnamed-2.jpg","_links":{"self":[{"href":"https:\/\/www.dancemogul.com\/news\/wp-json\/wp\/v2\/media\/8287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dancemogul.com\/news\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.dancemogul.com\/news\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.dancemogul.com\/news\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dancemogul.com\/news\/wp-json\/wp\/v2\/comments?post=8287"}]}}